{"id":5814,"date":"2025-11-19T15:12:12","date_gmt":"2025-11-19T07:12:12","guid":{"rendered":"https:\/\/www.goodworksemi.com\/?page_id=5814"},"modified":"2026-04-29T15:02:44","modified_gmt":"2026-04-29T07:02:44","slug":"schottky-diodes","status":"publish","type":"page","link":"https:\/\/www.goodworksemi.com\/ja\/products\/diodes\/schottky-diodes\/","title":{"rendered":"\u30b7\u30e7\u30c3\u30c8\u30ad\u30fc\u30c0\u30a4\u30aa\u30fc\u30c9"},"content":{"rendered":"<table style=\"border-collapse: collapse; width: 540.02pt;\" border=\"0\" width=\"720\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">\u54c1\u756a<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30c7\u30fc\u30bf\u30b7\u30fc\u30c8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">VRRM\uff08V\uff09<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">I(AV)A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">IFSM\uff08A\uff09<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">VF\uff08V\uff09<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">IF\uff08A\uff09<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">IR(uA)<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">VR\uff08V\uff09<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30d1\u30c3\u30b1\u30fc\u30b8\u6982\u8981<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K12<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K13<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K14<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K16<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K18<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K110<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K115<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K22<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K23<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K24<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K25<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K26<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K28<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K210<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K215<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K220<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K32<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K33<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K34<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K35<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K36<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K38<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K310<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K315<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K320<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K52<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K53<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K54<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K56<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K58<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K510<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K515<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">K520<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SOD123FL<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS12F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS13F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS14F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS15F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS16F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS18F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS110F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS115F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS120F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS22F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS23F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS24F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS25F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS26F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS28F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS210F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS215F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS220F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS32F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS33F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS34F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS35F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS36F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS38F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS310F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS315F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS320F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS52F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS53F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS54F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS55F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS56F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS58F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS510F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS515F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS520F<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMAF<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS22BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS23BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS24BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS25BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS26BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS28BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS210BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS215BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS220BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS32BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS33BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS34BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS35BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS36BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS38BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS310BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS315BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS320BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS52BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS53BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS54BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS55BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS56BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS58BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS510BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS515BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS520BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS84BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS86BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS810BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS815BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS820BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS1045BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS1060BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS1010BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">SS10150BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">SS10200BF<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30d3\u30fc\u30a8\u30d5<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS12A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS13A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS14A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS15A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS16A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS18A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS110A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS115A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS120A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS22A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS23A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS24A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS25A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS26A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS28A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS210A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS215A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS220A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS32A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS33A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS34A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS35A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS36A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS38A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS310A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS315A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS320A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS52A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS53A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS54A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS55A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS56A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS58A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS510A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS515A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS520A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK12A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK13A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK14A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK15A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK16A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK18A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK110A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK115A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK120A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK22A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK23A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK24A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK25A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK26A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK28A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK210A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK215A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK220A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK32A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK33A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK34A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK35A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK36A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK38A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK310A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK315A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK320A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK52A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK53A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK54A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK55A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK56A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK58A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK510A<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMA<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B240B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B260B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B2100B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B340B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B360B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B3100B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B540B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B560B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B5100B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS22B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS23B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS24B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS25B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS26B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS28B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS210B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS215B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS220B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS32B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS33B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS34B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS35B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS36B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS38B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS310B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS315B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS320B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS52B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS53B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS54B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS55B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS56B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS58B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS510B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS515B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS520B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS84B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS86B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS810B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS815B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS820B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS1045B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS1060B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS10100B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS10150B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS10200B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK22B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK23B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK24B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK25B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK26B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK28B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK210B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK215B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK220B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK32B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK33B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK34B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK35B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK36B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK38B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK310B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK315B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK320B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SM3150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SM3200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK52B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK53B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK54B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK55B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK56B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK58B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK510B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK515B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK520B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SM5150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SM5200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK84B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK86B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK810B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK815B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK820B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK1045B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK1060B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK10100B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK10150B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK10200B<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">SMB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B340C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B360C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B3100C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B540C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B560C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">B5100C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SM5150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SM5200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS32C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS33C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS34C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS35C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS36C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS38C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS310C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS315C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS320C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS52C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS53C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS54C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS55C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS56C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS58C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS510C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS515C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS520C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK32C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK33C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK34C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK35C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK36C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK38C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK310C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK315C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK320C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK52C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK53C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK54C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK55C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK56C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK58C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK510C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK515C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK520C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS82C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS83C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS84C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS85C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS86C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS88C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS810C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS815C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS820C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS1045C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS1060C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS10100C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS10150C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SS10200C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK82C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK83C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK84C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK85C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK86C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK88C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK810C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK815C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK820C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK1045C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK1060C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK10100C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK10150C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SK10200C<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">\u30a8\u30b9\u30a8\u30e0\u30b7\u30fc<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">10U45SP<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB845<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB860<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB8100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB8150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB8200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB1045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB1060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB10100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB10150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB10200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB1545<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB1560<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB15100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB15150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB15200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">15<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB2045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB2060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB20100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB20150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB20200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-277<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRD1045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRD1060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRD10100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRD10150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRD10200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRD2045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.6<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRD2060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRD20100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRD20150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRD20200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-252<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRS2045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.6<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRS2060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRS20100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRS20150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRS20200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">175<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRS3045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.6<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBRS3060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.75<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRS30100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRS30150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRS30200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.9<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.02<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-263<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1S20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">R-1<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1S30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">R-1<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1S40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">R-1<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1S50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">R-1<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1S60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">R-1<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1S80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">R-1<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1S100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">R-1<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR120S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR130S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR140S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR150S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR160S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR180S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR190S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1100S<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">A-405<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1N5817<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1N5818<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1N5819<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.6<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR120<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR130<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR140<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR180<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR190<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR220<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR230<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR240<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR260<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR280<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR290<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR2100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-41<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB220<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB230<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB240<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB260<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB280<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB290<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SB2100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR220<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR230<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR240<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR260<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR280<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR290<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR2100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR2150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR2200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-15<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1N5820<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.475<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1N5821<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">1N5822<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.525<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR320<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR330<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR340<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR350<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR360<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR380<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR390<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR3100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR3150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR3200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">3<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR520<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR530<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR540<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR550<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">50<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR560<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR580<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR590<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">90<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR5100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR5150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR5200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">5<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR820<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR840<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR860<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR880<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR8100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR8150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR8200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">160<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1020<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">170<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1040<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">170<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">170<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR1080<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">170<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR10100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">170<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR10150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">170<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">SR10200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">170<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">DO-27<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF820CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF845CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF860CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF880CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF8100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF8150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF8200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1020CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1045CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1060CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1080CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF10100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF10150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF10200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF2045CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF2060CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF20100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF20150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF20200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF3045CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF3060CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF30100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF30150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF30200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF820<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF845<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF860<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF880<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF8100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF8150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF8200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1020<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF1080<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF10100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF10150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF10200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF2045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF2060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF20100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF20150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF20200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF3045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF3060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF30100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF30150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBRF30200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">ITO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR820CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR845CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR860CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR880CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR8100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR8150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR8200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR1020CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR1045CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR1060CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR1080CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR10100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR10150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR10200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR2045CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR2060CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR20100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR20150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR20200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR3045CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR3060CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR30100CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR30150CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR30200CT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AB<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR820<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR845<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR860<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR880<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR8100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR8150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR8200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">8<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR1020<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR1045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR1060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR1080<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">80<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR10100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR10150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR10200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">10<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR2045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR2060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR20100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR20150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR20200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">20<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR3045<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR3060<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR30100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR30150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 14.25pt;\">\n<td class=\"et2\" style=\"height: 14.25pt; width: 54.00pt;\" width=\"72\" height=\"19\">MBR30200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-220AC<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR3045PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.55<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR3060PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR30100PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR30150PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR30200PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">250<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">30<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR4045PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.6<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR4060PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR40100PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR40150PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR40200PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR6040PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">40<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.6<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">45<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR6060PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.7<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.2<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR60100PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.85<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.1<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">100<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR60150PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">150<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<tr style=\"height: 28.50pt;\">\n<td class=\"et2\" style=\"height: 28.50pt; width: 54.00pt;\" width=\"72\" height=\"38\">MBR60200PT<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\"><\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">400<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.92<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">60<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">0.05<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" align=\"right\" width=\"72\">200<\/td>\n<td class=\"et2\" style=\"width: 54.00pt;\" width=\"72\">TO-247<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Part Number DATASHEET VRRM\uff08V\uff09 I(AV)A IFSM\uff08A\uff09 VF\uff08V\uff09 IF\uff08A\uff09 IR(uA) VR\uff08V\uff09 Package outline K12 20 1 30 0.45 1 0.2 20<\/p>","protected":false},"author":2,"featured_media":0,"parent":5658,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5814","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/pages\/5814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/comments?post=5814"}],"version-history":[{"count":2,"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/pages\/5814\/revisions"}],"predecessor-version":[{"id":14415,"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/pages\/5814\/revisions\/14415"}],"up":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/pages\/5658"}],"wp:attachment":[{"href":"https:\/\/www.goodworksemi.com\/ja\/wp-json\/wp\/v2\/media?parent=5814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}