{"id":387,"date":"2023-06-06T11:01:34","date_gmt":"2023-06-06T11:01:34","guid":{"rendered":"https:\/\/dummy.xtemos.com\/woodmart2\/furniture2\/?page_id=23"},"modified":"2026-01-02T03:11:56","modified_gmt":"2026-01-01T19:11:56","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.goodworksemi.com\/id\/about-us\/contact-us\/","title":{"rendered":"Hubungi Kami"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1765714115631 vc_row-o-equal-height vc_row-flex wd-rs-693ea8bd0476f\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-6 vc_col-md-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1496932335926\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6a04f159292d9\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-title-color-default wd-title-style-bordered text-left vc_custom_1484242758590 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >KIRIMKAN EMAIL KEPADA KAMI<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"13\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/id\/wp-json\/wp\/v2\/pages\/387#wpcf7-f13-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulir Pesan\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/id\/wp-json\/wp\/v2\/pages\/387#wpcf7-f13-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wd-grid-f-stretch\">\n\t<div class=\"wd-col\">\n\t\t<p><label>Nama Anda<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"wd-col\">\n\t\t<p><label>Email Anda<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"wd-grid-f-stretch\">\n\t<div class=\"wd-col\">\n\t\t<p><label>Nomor Telepon<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"wd-col\">\n\t\t<p><label>Perusahaan<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div>\n\t<p><label>Pesan Anda<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<div>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"Kirim\" \/>\n\t<\/p>\n<\/div>\n<div>\n\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">Silakan buktikan bahwa Anda adalah manusia dengan memilih<span> gelas<\/span>\u3002<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M488 313v143c0 13-11 24-24 24H348c-7 0-12-5-12-12V356c0-7-5-12-12-12h-72c-7 0-12 5-12 12v112c0 7-5 12-12 12H112c-13 0-24-11-24-24V313c0-4 2-7 4-10l188-154c5-4 11-4 16 0l188 154c2 3 4 6 4 10zm84-61l-84-69V44c0-6-5-12-12-12h-56c-7 0-12 6-12 12v73l-89-74a48 48 0 00-61 0L4 252c-5 4-5 12-1 17l25 31c5 5 12 5 17 1l235-193c5-4 11-4 16 0l235 193c5 5 13 4 17-1l25-31c4-6 4-13-1-17z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M192 384h192c53 0 96-43 96-96h32a128 128 0 000-256H120c-13 0-24 11-24 24v232c0 53 43 96 96 96zM512 96a64 64 0 010 128h-32V96h32zm48 384H48c-47 0-61-64-36-64h584c25 0 11 64-36 64z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"id\"\/><\/form>\n<\/div>\n<div class=\"vc-hoverbox-wrapper vc_custom_1763727103992 vc-hoverbox-shape--rounded vc-hoverbox-align--center vc-hoverbox-direction--default vc-hoverbox-width--100\"  ontouchstart=\"\">\n  <div class=\"vc-hoverbox\">\n    <div class=\"vc-hoverbox-inner\">\n      <div class=\"vc-hoverbox-block vc-hoverbox-front\" style=\"background-image: url(https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/banner-5-2-1024x392.jpg);\">\n        <div class=\"vc-hoverbox-block-inner vc-hoverbox-front-inner\">\n            \n        <\/div>\n      <\/div>\n      <div class=\"vc-hoverbox-block vc-hoverbox-back\" style=\"background-color: #ebebeb;\">\n        <div class=\"vc-hoverbox-block-inner vc-hoverbox-back-inner\">\n            <h2 style=\"text-align:center\">Basis kerja sama industri-akademisi-penelitian-kerja sama multi-pihak<\/h2>\n            <p data-start=\"90\" data-end=\"172\"><strong data-start=\"90\" data-end=\"172\">Menyediakan solusi aplikasi khusus kelas industri dan kelas otomotif<\/strong><\/p>\n\n            \n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-6 vc_col-md-6\"><div class=\"vc_column-inner vc_custom_1496932331302\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6a04f1592c5f0\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-title-color-default wd-title-style-bordered text-left vc_custom_1484251594500 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >PERTANYAAN YANG SERING DIAJUKAN<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-6956c64cdafbd\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-6956c64cdafbd text-left\">\n\t\t\t<p>Goodwork memiliki tenaga teknik dan teknis yang berpengalaman, serta tim manajemen yang profesional.<\/p>\n<p>Produk kami meliputi<strong><span style=\"color: #224385;\"> Dioda, Penyearah Jembatan, MOSFET, Transistor, Tiristor, Perlindungan baterai Lithium, Regulator Putus Rendah, Fotokopel<\/span><\/strong>, yang mencakup berbagai penelitian, pengembangan, produksi, dan penjualan independen.<\/p>\n<p>Semua produk telah lulus <strong><span style=\"color: #224385;\">UL AS, SGS, RoHS UE<\/span><\/strong>, dan <strong><span style=\"color: #224385;\">MENJANGKAU<\/span><\/strong> sertifikasi perlindungan lingkungan.<\/p>\n\t\t<\/div>\n\t\t\n\t\t<div id=\"wd-6a04f1592c6a1\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-title-color-default wd-title-style-bordered text-left vc_custom_1484253141262 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >HUBUNGI KAMI<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1484253288811\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-69204e611ca73\" class=\"wd-rs-69204e611ca73 wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-items-top vc_custom_1763725471505\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 40px;height: 40px;\"><img decoding=\"async\"  src=\"https:\/\/www.goodworksemi.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/w-cellphone.svg\" loading=\"lazy\" width=\"40\" height=\"40\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p><span style=\"color: #333333;\"><strong>Telepon:<\/strong><\/span> <a class=\"c-l-s-i-s Mobile\">+86-0755-83188488<\/a><br \/>\n<span style=\"color: #333333;\"><strong>Email:<\/strong><\/span> <a href=\"mailto:sivian@gkdiode.com\">sivian@gkdiode.com<\/a><\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-692052d5233e9\" class=\"wd-rs-692052d5233e9 wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-items-top vc_custom_1763726043997\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 40px;height: 40px;\"><img decoding=\"async\"  src=\"https:\/\/www.goodworksemi.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/w-chat.svg\" loading=\"lazy\" width=\"40\" height=\"40\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p><strong>Pemasok Elektronik Profesional untuk Proyek Anda Berikutnya.<\/strong><\/p>\n<p><a href=\"https:\/\/api.whatsapp.com\/send?phone=8617796315616\"><strong>WhatsApp:+8617796315616<\/strong><\/a><\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-61260fc4ec6cd\" class=\"wd-rs-61260fc4ec6cd wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-items-top vc_custom_1629884363638\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 45px;height: 45px;\"><img decoding=\"async\"  src=\"https:\/\/www.goodworksemi.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/w-airplane.svg\" loading=\"lazy\" width=\"45\" height=\"45\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p><span style=\"color: #333333;\"><strong>Forum dukungan<\/strong><\/span><br \/>\n<span style=\"color: #333333;\"><strong>selama lebih dari 24 jam<\/strong><\/span><\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-6923c8595702e\" class=\"wd-rs-6923c8595702e wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-items-top vc_custom_1763952742486\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 40px;height: 40px;\"><img decoding=\"async\"  src=\"https:\/\/www.goodworksemi.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/w-map-placeholder.svg\" loading=\"lazy\" width=\"40\" height=\"40\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p><span style=\"color: #333333;\"><strong>Alamat: <\/strong><\/span> <a class=\"c-l-s-i-s WebSit1\">Unit 1006-1010, Blok C, Pusat Inovasi Digital, No. 328 Mintang Road, Jalan Minzhi, Distrik Longhua, Shenzhen, Guangdong, Tiongkok<\/a><\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey vc_custom_1484254145420\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t<div id=\"wd-61260e3e08751\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-61260e3e08751 text-left wd-font-weight-600 color-title\">\n\t\t\t<p>Apakah Anda memiliki pertanyaan tentang bagaimana kami dapat membantu perusahaan Anda?<br \/>\n<span style=\"color: #83b735;\"><a style=\"color: #83b735;\" href=\"#\">Kirimkan email kepada kami dan kami akan segera menghubungi Anda.<\/a><\/span><\/p>\n\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"SEND US AN EMAIL Your Name Your Email Phone Number Company Your Message Please prove you are human by selecting","protected":false},"author":1,"featured_media":0,"parent":385,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-387","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/pages\/387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/comments?post=387"}],"version-history":[{"count":0,"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/pages\/387\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/pages\/385"}],"wp:attachment":[{"href":"https:\/\/www.goodworksemi.com\/id\/wp-json\/wp\/v2\/media?parent=387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}