{"id":91,"count":158,"description":"","link":"https:\/\/www.goodworksemi.com\/es\/categoria-producto\/diodes\/fast-recovery-diodes\/","name":"Diodos de recuperaci\u00f3n r\u00e1pida","slug":"fast-recovery-diodes","taxonomy":"product_cat","parent":73,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodworksemi.com\/es\/wp-json\/wp\/v2\/product_cat\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodworksemi.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.goodworksemi.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/es\/wp-json\/wp\/v2\/product_cat\/73"}],"wp:post_type":[{"href":"https:\/\/www.goodworksemi.com\/es\/wp-json\/wp\/v2\/product?product_cat=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}