{"id":5639,"date":"2025-11-19T04:54:16","date_gmt":"2025-11-18T20:54:16","guid":{"rendered":"https:\/\/www.goodworksemi.com\/?page_id=5639"},"modified":"2025-12-21T17:38:43","modified_gmt":"2025-12-21T09:38:43","slug":"design-support","status":"publish","type":"page","link":"https:\/\/www.goodworksemi.com\/ar\/design-support\/","title":{"rendered":"\u062f\u0639\u0645 \u0627\u0644\u062a\u0635\u0645\u064a\u0645"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><section data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_section vc_custom_1763994285219 vc_section-has-fill wd-rs-69246aa232be3\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1499604445501 vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-6 wd-rs-6124f66cebd97\"><div class=\"vc_column-inner vc_custom_1629812334714\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1499603294997 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1499604113587\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"woodmart-counter wd-wpb  wd-rs-69201971b95a2 counter-large text-center color-scheme-light\" id=\"wd-69201971b95a2\">\n\t\t\t\t<div class=\"counter-value wd-font-weight-600\" data-state=\"new\" data-final=\"25\">\n\t\t\t\t\t0\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"counter-label\">\u0645\u0633\u0627\u062d\u0629 \u0627\u0644\u0641\u062f\u0627\u0646<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 wd-rs-6124f4e81cd40\"><div class=\"vc_column-inner vc_custom_1629811947019\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"woodmart-counter wd-wpb  wd-rs-69201bf23f40a counter-large text-center color-scheme-light\" id=\"wd-69201bf23f40a\">\n\t\t\t\t<div class=\"counter-value wd-font-weight-600\" data-state=\"new\" data-final=\"20000\">\n\t\t\t\t\t0\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"counter-label\">\u0645\u0633\u0627\u062d\u0629 \u0627\u0644\u0645\u0635\u0646\u0639 (\u0645\u00b2)<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1499603294997 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1499604519781\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"woodmart-counter wd-wpb  wd-rs-69201bf0e0b05 counter-large text-center color-scheme-light\" id=\"wd-69201bf0e0b05\">\n\t\t\t\t<div class=\"counter-value wd-font-weight-600\" data-state=\"new\" data-final=\"20\">\n\t\t\t\t\t0\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"counter-label\">\u062a\u063a\u0644\u064a\u0641 \u0627\u0644\u0631\u0642\u0627\u0626\u0642 \u0648\u062e\u0637\u0648\u0637 \u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6\"><div class=\"vc_column-inner vc_custom_1499604526470\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"woodmart-counter wd-wpb  wd-rs-69201d33a9eb5 counter-large text-center color-scheme-light\" id=\"wd-69201d33a9eb5\">\n\t\t\t\t<div class=\"counter-value wd-font-weight-600\" data-state=\"new\" data-final=\"30\">\n\t\t\t\t\t0\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"counter-label\">\u062e\u0637\u0648\u0637 \u0641\u0627\u064a \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u0633\u0631\u0639\u0629<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1499603310379\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1499604535206\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"woodmart-counter wd-wpb  wd-rs-69201dcf60c33 counter-large text-center color-scheme-light\" id=\"wd-69201dcf60c33\">\n\t\t\t\t<div class=\"counter-value wd-font-weight-600\" data-state=\"new\" data-final=\"30000\">\n\t\t\t\t\t0\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"counter-label\">\u0645\u0633\u0627\u062d\u0629 \u062a\u062e\u0632\u064a\u0646 \u0630\u0643\u064a\u0629 \uff08\u0645\u00b2\uff09<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6\"><div class=\"vc_column-inner vc_custom_1499604548790\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"woodmart-counter wd-wpb  wd-rs-69201e1c56868 counter-large text-center color-scheme-light\" id=\"wd-69201e1c56868\">\n\t\t\t\t<div class=\"counter-value wd-font-weight-600\" data-state=\"new\" data-final=\"300\">\n\t\t\t\t\t0\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"counter-label\">\u0627\u0644\u0645\u0648\u0638\u0641\u0648\u0646<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 wd-rs-6124f4d14c35c\"><div class=\"vc_column-inner vc_custom_1629811925592\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6a04d64330b81\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-title-color-white wd-title-style-default text-left vc_custom_1499675347819 wd-width-enabled wd-underline-colored\" style=\"--wd-max-width: 90%;\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xxxl\" >\u0646\u062d\u0648\u0644 \u0641\u0643\u0631\u062a\u0643 \u0625\u0644\u0649 \u062d\u0642\u064a\u0642\u0629 \u0648\u0627\u0642\u0639\u0629.<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-6920220078c96\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-6920220078c96 hidden-md hidden-sm hidden-xs text-left color-scheme-light wd-fontsize-custom vc_custom_1763713626257\">\n\t\t\t<p>\u062a\u0634\u0643\u064a\u0644 \u0645\u0633\u062a\u0642\u0628\u0644 \u0645\u0633\u062a\u062f\u0627\u0645<\/p>\n\t\t<\/div>\n\t\t\t\t<div id=\"wd-69201ed7dcc6a\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-69201ed7dcc6a text-left color-scheme-light wd-fontsize-custom vc_custom_1763712989190\">\n\t\t\t<p>\u0641\u064a \u0627\u0644\u0648\u0642\u062a \u0627\u0644\u062d\u0627\u0644\u064a\u060c \u0623\u0646\u0634\u0623\u0646\u0627 \u0623\u0643\u062b\u0631 \u0645\u0646 20 \u062e\u0637\u064b\u0627 \u0644\u062a\u0639\u0628\u0626\u0629 \u0648\u0627\u062e\u062a\u0628\u0627\u0631 \u0627\u0644\u0631\u0642\u0627\u0626\u0642\u060c \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0623\u0643\u062b\u0631 \u0645\u0646 30 \u062e\u0637 \u0625\u0646\u062a\u0627\u062c \u0645\u0624\u062a\u0645\u062a \u0628\u0627\u0644\u0643\u0627\u0645\u0644 \u0648\u0639\u0627\u0644\u064a \u0627\u0644\u0633\u0631\u0639\u0629. \u0648\u0642\u062f \u062d\u0635\u0644 \u0627\u0644\u0645\u0635\u0646\u0639 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0629 \u0646\u0638\u0627\u0645 \u0627\u0644\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u062f\u0648\u0644\u064a\u0629 ISO9001 \u3001 ISO14001 \u3001 IATF16949. \u064a\u063a\u0637\u064a \u0645\u0633\u0627\u062d\u0629 25 \u0641\u062f\u0627\u0646\u064b\u0627\u060c \u0648\u0645\u0633\u0627\u062d\u0629 \u0627\u0644\u0645\u0635\u0646\u0639 20,000 \u0645\u062a\u0631 \u0645\u0631\u0628\u0639\u060c \u0648\u0645\u0633\u0627\u062d\u0629 \u062a\u062e\u0632\u064a\u0646 \u0630\u0643\u064a\u0629 \u062a\u0628\u0644\u063a 3,00 \u0645\u062a\u0631 \u0645\u0631\u0628\u0639.<\/p>\n\t\t<\/div>\n\t\t<div id=\"wd-69445f4c39db5\" class=\"wd-rs-69445f4c39db5  wd-button-wrapper text-center inline-element\"><a href=\"https:\/\/www.goodworksemi.com\/sample-request\/\" title=\"\" class=\"btn btn-color-white btn-style-default btn-shape-rectangle btn-size-default\">\u0637\u0644\u0628 \u0639\u064a\u0646\u0629<\/a><\/div><div id=\"wd-69445f5ea8a9f\" class=\"wd-rs-69445f5ea8a9f  wd-button-wrapper text-center inline-element\"><a href=\"https:\/\/www.goodworksemi.com\/about-us\/contact-us\/\" title=\"\" class=\"btn btn-color-white btn-style-bordered btn-shape-rectangle btn-size-default\">\u0627\u0628\u062f\u0623 \u0645\u0634\u0631\u0648\u0639\u0643<\/a><\/div><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid wd-disable-overflow wd-rs-693eaa7f98bc2\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-69246d0e5d236\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-69246d0e5d236 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xxl\" >\u062e\u062f\u0645\u0627\u062a \u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0627\u0644\u062c\u0627\u0647\u0632\u0629<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<\/div><\/div><\/div><\/div><div data-vc-parallax=\"1.5\" class=\"vc_row wpb_row vc_row-fluid vc_row-has-fill vc_general vc_parallax vc_parallax-content-moving wd-rs-6920874c01a81\"><div class=\"wpb_column wpb_animate_when_almost_visible wpb_wd-zoom-in wd-zoom-in vc_column_container vc_col-sm-4 wd-rs-6920890d0010e\"><div class=\"vc_column-inner vc_custom_1763739934149\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1763739852153 vc_row-has-fill wd-rs-692088be25b8a\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-692183471e9cd\" class=\"wd-image wd-wpb wd-rs-692183471e9cd text-center\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"698\" height=\"480\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-1-.jpg\" class=\"attachment-260X260 size-260X260\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-1-.jpg 698w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-1--300x206.jpg 300w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div id=\"wd-6923c67c5d994\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6923c67c5d994 wd-title-color-default wd-title-style-default text-left wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-600 wd-fontsize-m\" >\u0623\u062c\u0647\u0632\u0629 \u0623\u0634\u0628\u0627\u0647 \u0627\u0644\u0645\u0648\u0635\u0644\u0627\u062a \u0627\u0644\u0645\u0646\u0641\u0635\u0644\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u062a\u0648\u0641\u0631 Goodwork \u0645\u0643\u0648\u0646\u0627\u062a \u0623\u0634\u0628\u0627\u0647 \u0627\u0644\u0645\u0648\u0635\u0644\u0627\u062a \u0627\u0644\u0645\u0646\u0641\u0635\u0644\u0629 \u0645\u0646 \u0627\u0644\u062f\u0631\u062c\u0629 \u0627\u0644\u0647\u0646\u062f\u0633\u064a\u0629\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0627\u0644\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0648\u0645\u0648\u0632\u0641\u064a\u062a\u0627\u062a MOSFET \u0648\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0634\u0648\u062a\u0643\u064a \u0648\u0623\u062c\u0647\u0632\u0629 \u062d\u0645\u0627\u064a\u0629 TVS \u0648\u0645\u0642\u0648\u0645\u0627\u062a \u0627\u0644\u062c\u0633\u0648\u0631 \u0648\u0623\u062c\u0632\u0627\u0621 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0637\u0627\u0642\u0629. \u0635\u064f\u0645\u0645\u062a \u0623\u062c\u0647\u0632\u062a\u0646\u0627 \u0644\u062a\u062d\u0642\u064a\u0642 \u0627\u0644\u0645\u0648\u062b\u0648\u0642\u064a\u0629 \u0627\u0644\u0639\u0627\u0644\u064a\u0629 \u0648\u0627\u0644\u0623\u062f\u0627\u0621 \u0627\u0644\u0645\u062a\u0633\u0642 \u0641\u064a \u0627\u0644\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629 \u0648\u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a \u0648\u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a \u0627\u0644\u0627\u0633\u062a\u0647\u0644\u0627\u0643\u064a\u0629.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-6928417a4b6c7\" class=\"wd-rs-6928417a4b6c7 wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn wd-items-top with-btn box-btn-static\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><\/div>\n\n\t\t\t\t\t\t<div class=\"info-btn-wrapper\"><div id=\"wd-6a04d64337f4c\" class=\"wd-button-wrapper text-left\"><a href=\"https:\/\/www.goodworksemi.com\/about-us\/company\/\" title=\"\" class=\"btn btn-color-primary btn-style-link btn-shape-rectangle btn-size-extra-large btn-icon-pos-right\">\u0627\u0639\u0631\u0641 \u0627\u0644\u0645\u0632\u064a\u062f<span class=\"wd-btn-icon\"><img decoding=\"async\" width=\"25\" height=\"25\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304-25x25.png\" class=\"attachment-25x25 size-25x25\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304-25x25.png 25w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304.png 30w\" sizes=\"(max-width: 25px) 100vw, 25px\" \/><\/span><\/a><\/div><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<style><\/style>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill wd-rs-6920898aac712\"><div class=\"vc_column-inner vc_custom_1763740049691\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1763739852153 vc_row-has-fill wd-rs-692088be25b8a\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-69217f643c251\" class=\"wd-image wd-wpb wd-rs-69217f643c251 text-center\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"698\" height=\"480\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-repairing-computer-.jpg\" class=\"attachment-260X260 size-260X260\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-repairing-computer-.jpg 698w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-repairing-computer--300x206.jpg 300w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div id=\"wd-6923c6888ea1e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6923c6888ea1e wd-title-color-default wd-title-style-default text-left wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-600 wd-fontsize-m\" >\u0627\u0644\u062f\u0639\u0645 \u0627\u0644\u0647\u0646\u062f\u0633\u064a \u0648\u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0627\u0644\u0647\u0646\u062f\u0633\u064a<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u0646\u062d\u0646 \u0646\u062f\u0639\u0645 \u0627\u0644\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u062e\u0644\u0627\u0644 \u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u062a\u0637\u0648\u064a\u0631 \u0628\u0623\u0643\u0645\u0644\u0647\u0627 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0625\u0631\u0634\u0627\u062f\u0627\u062a \u0639\u0645\u0644\u064a\u0629 \u062d\u0648\u0644 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062c\u0647\u0627\u0632\u060c \u0648\u0633\u0644\u0648\u0643 \u0627\u0644\u062f\u0627\u0626\u0631\u0629\u060c \u0648\u0646\u0645\u0630\u062c\u0629 SPICE\u060c \u0648\u0627\u0644\u0627\u0639\u062a\u0628\u0627\u0631\u0627\u062a \u0627\u0644\u062d\u0631\u0627\u0631\u064a\u0629\u060c \u0648\u062d\u0645\u0627\u064a\u0629 EMI \u0648ESD\u060c \u0648\u0627\u0644\u0645\u0648\u062b\u0648\u0642\u064a\u0629 \u0637\u0648\u064a\u0644\u0629 \u0627\u0644\u0623\u062c\u0644. \u064a\u0639\u0645\u0644 \u0641\u0631\u064a\u0642 Goodwork \u0639\u0646 \u0643\u062b\u0628 \u0628\u062f\u0621\u0627\u064b \u0645\u0646 \u0627\u0644\u0645\u0631\u0627\u062c\u0639\u0627\u062a \u0627\u0644\u0645\u0628\u0643\u0631\u0629 \u0644\u0644\u062a\u0635\u0645\u064a\u0645 \u0648\u062d\u062a\u0649 \u0636\u0628\u0637 \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0644\u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0641\u064a \u0636\u0645\u0627\u0646 \u0623\u062f\u0627\u0621 \u0645\u062a\u0633\u0642 \u064a\u0645\u0643\u0646 \u0627\u0644\u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0644\u064a\u0647.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-693eaa1ab51a8\" class=\"wd-rs-693eaa1ab51a8 wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn wd-items-top with-btn box-btn-static\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><\/div>\n\n\t\t\t\t\t\t<div class=\"info-btn-wrapper\"><div id=\"wd-6a04d6433b6ea\" class=\"wd-button-wrapper text-left\"><a href=\"https:\/\/www.goodworksemi.com\/design-support\/\" title=\"\" class=\"btn btn-color-primary btn-style-link btn-shape-rectangle btn-size-extra-large btn-icon-pos-right\">\u0627\u0639\u0631\u0641 \u0627\u0644\u0645\u0632\u064a\u062f<span class=\"wd-btn-icon\"><img decoding=\"async\" width=\"25\" height=\"25\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304-25x25.png\" class=\"attachment-25x25 size-25x25\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304-25x25.png 25w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304.png 30w\" sizes=\"(max-width: 25px) 100vw, 25px\" \/><\/span><\/a><\/div><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<style><\/style>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 vc_col-has-fill wd-rs-69208976c658c\"><div class=\"vc_column-inner vc_custom_1763740039803\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1763739852153 vc_row-has-fill wd-rs-692088be25b8a\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-69218519cafb0\" class=\"wd-image wd-wpb wd-rs-69218519cafb0 text-center\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"698\" height=\"480\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-2-.jpg\" class=\"attachment-260X260 size-260X260\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-2-.jpg 698w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/technician-2--300x206.jpg 300w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div id=\"wd-6923c69a251fc\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6923c69a251fc wd-title-color-default wd-title-style-default text-left wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-600 wd-fontsize-m\" >\u062e\u0628\u0631\u0629 \u0645\u062b\u0628\u062a\u0629 \u0641\u064a \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0627\u0644\u062a\u0637\u0628\u064a\u0642<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u0648\u0628\u062f\u0639\u0645 \u0645\u0646 \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u0645\u0639\u062a\u0645\u062f (UL \u0648 RoHS \u0648 ISO9001) \u0648\u0627\u0644\u0642\u062f\u0631\u0629 \u0627\u0644\u0642\u0648\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0628\u062d\u062b \u0648\u0627\u0644\u062a\u0637\u0648\u064a\u0631\u060c \u062a\u0636\u0645\u0646 Goodwork \u0623\u062f\u0627\u0621\u064b \u0645\u0633\u062a\u0642\u0631\u064b\u0627 \u0648\u062c\u0627\u0647\u0632\u064b\u0627 \u0644\u0644\u062a\u0637\u0628\u064a\u0642. \u062a\u064f\u0633\u062a\u062e\u062f\u0645 \u062d\u0644\u0648\u0644\u0646\u0627 \u0639\u0644\u0649 \u0646\u0637\u0627\u0642 \u0648\u0627\u0633\u0639 \u0641\u064a \u0625\u0645\u062f\u0627\u062f\u0627\u062a \u0627\u0644\u0637\u0627\u0642\u0629 \u0648\u0627\u0644\u0623\u062a\u0645\u062a\u0629 \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629 \u0648\u0627\u0644\u062a\u062d\u0643\u0645 \u0641\u064a \u0627\u0644\u0645\u062d\u0631\u0643\u0627\u062a \u0648\u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a \u0627\u0644\u0627\u0633\u062a\u0647\u0644\u0627\u0643\u064a\u0629 \u0648\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0627\u062a \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a\u060c \u0645\u0645\u0627 \u064a\u062c\u0639\u0644\u0646\u0627 \u0634\u0631\u064a\u0643\u064b\u0627 \u0645\u0648\u062b\u0648\u0642\u064b\u0627 \u0628\u0647 \u0644\u062a\u062d\u0633\u064a\u0646 \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0646\u0638\u0627\u0645.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-693eaa3617e9c\" class=\"wd-rs-693eaa3617e9c wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn wd-items-top with-btn box-btn-static\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><\/div>\n\n\t\t\t\t\t\t<div class=\"info-btn-wrapper\"><div id=\"wd-6a04d6433e966\" class=\"wd-button-wrapper text-left\"><a href=\"https:\/\/www.goodworksemi.com\/quality-reliability\/\" title=\"\" class=\"btn btn-color-primary btn-style-link btn-shape-rectangle btn-size-extra-large btn-icon-pos-right\">\u0627\u0639\u0631\u0641 \u0627\u0644\u0645\u0632\u064a\u062f<span class=\"wd-btn-icon\"><img decoding=\"async\" width=\"25\" height=\"25\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304-25x25.png\" class=\"attachment-25x25 size-25x25\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304-25x25.png 25w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/jiantou-1-e1768980001304.png 30w\" sizes=\"(max-width: 25px) 100vw, 25px\" \/><\/span><\/a><\/div><\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<style><\/style>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid wd-rs-6947ba020f7e7\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill wd-rs-69218976eec26\"><div class=\"vc_column-inner vc_custom_1763805570671\"><div class=\"wpb_wrapper\"><div class=\"vc_tta-container\" data-vc-action=\"collapse\" data-vc-tta-autoplay=\"{&quot;delay&quot;:3000}\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-grey vc_tta-style-classic vc_tta-shape-rounded vc_tta-spacing-1 vc_tta-tabs-position-top vc_tta-controls-align-left\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\" role=\"tablist\"><li class=\"vc_tta-tab vc_active\" data-vc-tab role=\"presentation\"><a href=\"#1763741261637-608286bc-8800\" data-vc-tabs data-vc-container=\".vc_tta\" role=\"tab\" aria-selected=\"false\" id=\"tab-1763741261637-608286bc-8800\"><span class=\"vc_tta-title-text\">\u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u062c\u0648\u062f\u0629<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab role=\"presentation\"><a href=\"#1763741261668-20201cd5-e2d9\" data-vc-tabs data-vc-container=\".vc_tta\" role=\"tab\" aria-selected=\"false\" id=\"tab-1763741261668-20201cd5-e2d9\"><span class=\"vc_tta-title-text\">\u0646\u0638\u0627\u0645 \u0627\u0644\u062a\u062d\u0643\u0645 \u0627\u0644\u0628\u064a\u0626\u064a<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab role=\"presentation\"><a href=\"#1763741684257-d45336f1-da30\" data-vc-tabs data-vc-container=\".vc_tta\" role=\"tab\" aria-selected=\"false\" id=\"tab-1763741684257-d45336f1-da30\"><span class=\"vc_tta-title-text\">\u0627\u0644\u0639\u0645\u0644\u064a\u0629<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"1763741261637-608286bc-8800\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1763741261637-608286bc-8800\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u062c\u0648\u062f\u0629<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1763741496819 vc_row-has-fill wd-rs-69208f2d142a0\"><div class=\"wpb_column vc_column_container vc_col-sm-8 wd-rs-69209064a6595\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-6921892a2ae3b\" class=\"wd-image wd-wpb wd-rs-6921892a2ae3b text-center\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process.png 2560w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process-1200x675.png 1200w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process-300x169.png 300w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process-1024x576.png 1024w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process-768x432.png 768w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process-1536x864.png 1536w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/Handling-process-2048x1152.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-692408219077e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-692408219077e wd-title-color-default wd-title-style-default text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0627\u0644\u062a\u0639\u0627\u0645\u0644 \u0645\u0639 \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u062c\u0648\u062f\u0629<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<dl>\n<dt>\n<h5><strong>\u00a0\u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0644\u0649 \u0639\u0645\u0644\u064a\u0629 \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u0639\u0645\u0644\u0627\u0621:<\/strong><\/h5>\n<\/dt>\n<dd>\u064a\u0648\u0636\u062d \u0647\u0630\u0627 \u0627\u0644\u0645\u062e\u0637\u0637 \u0627\u0644\u0627\u0646\u0633\u064a\u0627\u0628\u064a \u0627\u0644\u0639\u0645\u0644\u064a\u0629 \u0627\u0644\u0634\u0627\u0645\u0644\u0629 \u0628\u062f\u0621\u064b\u0627 \u0645\u0646 \u0648\u0631\u0648\u062f \u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0627\u0644\u0639\u0645\u064a\u0644 \u0648\u062d\u062a\u0649 \u0625\u063a\u0644\u0627\u0642 \u062d\u0627\u0644\u0629 \u0627\u0644\u0645\u0644\u0627\u062d\u0638\u0627\u062a\u060c \u0645\u0639 \u062a\u0633\u0644\u064a\u0637 \u0627\u0644\u0636\u0648\u0621 \u0639\u0644\u0649 \u0627\u0644\u062a\u0639\u0627\u0648\u0646 \u0628\u064a\u0646 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0648\u0642\u0633\u0645 \u0636\u0645\u0627\u0646 \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0627\u0644\u0623\u0642\u0633\u0627\u0645 \u0627\u0644\u0648\u0638\u064a\u0641\u064a\u0629 \u0630\u0627\u062a \u0627\u0644\u0635\u0644\u0629.<\/dd>\n<\/dl>\n<dl>\n<dt>\n<h5><strong>\u062f\u0648\u0631 \u062a\u0623\u0643\u064a\u062f \u0627\u0644\u0639\u0645\u064a\u0644 \u0641\u064a \u062a\u0623\u0643\u064a\u062f \u0627\u0644\u0639\u0645\u064a\u0644:<\/strong><\/h5>\n<\/dt>\n<dd>\u062a\u0623\u0643\u064a\u062f \u0627\u0644\u0639\u0645\u064a\u0644 \u0623\u0645\u0631 \u0628\u0627\u0644\u063a \u0627\u0644\u0623\u0647\u0645\u064a\u0629 \u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0645\u0644\u0627\u062d\u0638\u0627\u062a \u0648\u062a\u062d\u062f\u064a\u062f \u0625\u062c\u0631\u0627\u0621\u0627\u062a \u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u062c\u0648\u062f\u0629.<\/dd>\n<\/dl>\n<dl>\n<dt>\n<h5><strong>\u062a\u062f\u0627\u0628\u064a\u0631 \u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0627\u0644\u062a\u062d\u0633\u064a\u0646:<\/strong><\/h5>\n<\/dt>\n<dd>\u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0627\u0644\u0641\u0639\u0627\u0644\u0629 \u0648\u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u0625\u062c\u0631\u0627\u0621\u0627\u062a \u0627\u0644\u062a\u0635\u062d\u064a\u062d\u064a\u0629 \u0644\u0645\u0646\u0639 \u062a\u0643\u0631\u0627\u0631 \u0627\u0644\u0645\u0634\u0643\u0644\u0627\u062a \u0641\u064a \u0634\u0631\u0643\u0629 Goodwork.<\/dd>\n<\/dl>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"wd-6924691aef28a\" class=\"wd-rs-6924691aef28a vc_custom_1763993907326 wd-button-wrapper wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn text-center\"><a href=\"https:\/\/www.goodworksemi.com\/about-us\/contact-us\/\" title=\"\" class=\"btn btn-style-default btn-shape-rectangle btn-size-default\">\u0627\u062a\u0635\u0644 \u0628\u0646\u0627<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1763741261668-20201cd5-e2d9\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1763741261668-20201cd5-e2d9\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u0646\u0638\u0627\u0645 \u0627\u0644\u062a\u062d\u0643\u0645 \u0627\u0644\u0628\u064a\u0626\u064a<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1763741496819 vc_row-has-fill wd-rs-69208f2d142a0\"><div class=\"wpb_column vc_column_container vc_col-sm-8 wd-rs-6920906da5c24\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-69218a599e0d8\" class=\"wd-image wd-wpb wd-rs-69218a599e0d8 text-center\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control.png 2560w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control-1200x675.png 1200w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control-300x169.png 300w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control-1024x576.png 1024w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control-768x432.png 768w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control-1536x864.png 1536w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/control-2048x1152.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6922822107450\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6922822107450 wd-title-color-default wd-title-style-default text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0646\u0638\u0627\u0645 \u0627\u0644\u062a\u062d\u0643\u0645 \u0627\u0644\u0628\u064a\u0626\u064a<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<dl>\n<dt>\n<h5><strong>\u0627\u0644\u0625\u0637\u0627\u0631 \u0627\u0644\u0634\u0627\u0645\u0644 \u0644\u0644\u0631\u0642\u0627\u0628\u0629 \u0627\u0644\u0628\u064a\u0626\u064a\u0629 \u0627\u0644\u0634\u0627\u0645\u0644\u0629:<\/strong><\/h5>\n<\/dt>\n<dd>\u0646\u0636\u0639 \u0645\u0639\u0627\u064a\u064a\u0631 \u062a\u062a\u0645\u0627\u0634\u0649 \u0645\u0639 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0648\u0627\u0644\u0644\u0648\u0627\u0626\u062d \u0627\u0644\u062a\u0646\u0638\u064a\u0645\u064a\u0629. \u062a\u0636\u0645\u0646 \u0627\u062a\u0641\u0627\u0642\u064a\u0629 \u0627\u0644\u062d\u0645\u0627\u064a\u0629 \u0639\u0646\u062f \u062a\u0623\u0643\u064a\u062f \u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0645\u062a\u062b\u0627\u0644 \u0633\u062c\u0644\u0627\u062a \u0627\u0644\u062a\u0648\u0631\u064a\u062f \u0648\u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0644\u0644\u0645\u0635\u0627\u062f\u0631 \u0648\u0627\u0644\u062a\u0642\u064a\u064a\u0645.<\/dd>\n<\/dl>\n<dl>\n<dt>\n<h5><strong>\u0627\u0644\u062a\u0639\u0627\u0648\u0646 \u0645\u0639 \u0627\u0644\u0645\u0648\u0631\u062f\u064a\u0646 \u0648\u0627\u0644\u0636\u0645\u0627\u0646 \u0627\u0644\u0633\u0646\u0648\u064a:<\/strong><\/h5>\n<\/dt>\n<dd>\u064a\u0648\u0642\u0651\u0639 \u0627\u0644\u0645\u0648\u0631\u062f\u0648\u0646 \u0639\u0644\u0649 \u0627\u0644\u062a\u0632\u0627\u0645\u0627\u062a \u0628\u064a\u0626\u064a\u0629 \u0648\u064a\u0642\u062f\u0645\u0648\u0646 \u0634\u0647\u0627\u062f\u0627\u062a \u0627\u0644\u0645\u0648\u0627\u062f. \u062a\u062a\u062d\u0642\u0642 \u062a\u0642\u0627\u0631\u064a\u0631 \u0627\u0644\u0637\u0631\u0641 \u0627\u0644\u062b\u0627\u0644\u062b \u0627\u0644\u0633\u0646\u0648\u064a\u0629 \u0645\u0646 \u0627\u0644\u0645\u0648\u0627\u062f \u0648\u062a\u062f\u0639\u0645 \u0634\u0641\u0627\u0641\u064a\u0629 \u0633\u0644\u0633\u0644\u0629 \u0627\u0644\u062a\u0648\u0631\u064a\u062f.<\/dd>\n<\/dl>\n<dl>\n<dt>\n<h5><strong>\u0627\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0637\u0631\u0641 \u062b\u0627\u0644\u062b \u0645\u0639\u062a\u0645\u062f:<\/strong><\/h5>\n<\/dt>\n<dd>\u062a\u062e\u0636\u0639 \u0627\u0644\u0645\u0648\u0627\u062f \u0644\u0627\u062e\u062a\u0628\u0627\u0631 ROHS \u0648REACH \u0645\u0646 \u0642\u0628\u0644 \u0645\u062e\u062a\u0628\u0631\u0627\u062a \u0645\u0639\u062a\u0645\u062f\u0629. \u062a\u0648\u0641\u0631 \u0627\u0644\u062a\u0642\u0627\u0631\u064a\u0631 \u0641\u064a \u0645\u0631\u062d\u0644\u062a\u064a \u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0648\u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0627\u0644\u0636\u062e\u0645 \u062f\u0644\u064a\u0644\u0627\u064b \u0639\u0644\u0649 \u0627\u0644\u0627\u0645\u062a\u062b\u0627\u0644 \u0648\u062a\u0639\u0632\u0632 \u062b\u0642\u0629 \u0627\u0644\u0639\u0645\u0644\u0627\u0621.<\/dd>\n<\/dl>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"wd-6924693831055\" class=\"wd-rs-6924693831055 vc_custom_1763993931274 wd-button-wrapper wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn text-center\"><a href=\"https:\/\/www.goodworksemi.com\/about-us\/contact-us\/\" title=\"\" class=\"btn btn-style-default btn-shape-rectangle btn-size-default\">\u0627\u062a\u0635\u0644 \u0628\u0646\u0627<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1763741684257-d45336f1-da30\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1763741684257-d45336f1-da30\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">\u0627\u0644\u0639\u0645\u0644\u064a\u0629<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1763741496819 vc_row-has-fill wd-rs-69208f2d142a0\"><div class=\"wpb_column vc_column_container vc_col-sm-8 wd-rs-69209074a7053\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-69218aa49a84c\" class=\"wd-image wd-wpb wd-rs-69218aa49a84c text-center\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1440\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1.png 2560w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1-1200x675.png 1200w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1-300x169.png 300w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1-1024x576.png 1024w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1-768x432.png 768w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1-1536x864.png 1536w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/process-1-2048x1152.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6922837082e9d\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6922837082e9d wd-title-color-default wd-title-style-default text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0627\u0644\u0639\u0645\u0644\u064a\u0629<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<dl>\n<dt>\n<h5><strong>\u0633\u064a\u0631 \u0639\u0645\u0644 \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u0645\u062a\u0643\u0627\u0645\u0644:<\/strong><\/h5>\n<\/dt>\n<dd>\u064a\u0628\u062f\u0623 \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u0628\u062a\u062c\u0647\u064a\u0632 \u0648\u062d\u062f\u0629 \u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u0645\u0631\u0643\u0632\u064a\u0629 \u0648\u0627\u0644\u062a\u062b\u0642\u064a\u0628 \u0648\u0627\u0644\u0644\u062d\u0627\u0645 \u0644\u062a\u0634\u0643\u064a\u0644 \u0627\u0644\u0645\u0643\u0648\u0646\u0627\u062a. \u062a\u0636\u0645\u0646 \u0627\u0644\u062c\u062f\u0648\u0644\u0629 \u0627\u0644\u0632\u0645\u0646\u064a\u0629 \u0644\u0644\u0642\u0648\u0644\u0628\u0629 \u0648\u0627\u0644\u0640 PMC \u0627\u0644\u0625\u0646\u062a\u0627\u062c\u064a\u0629 \u0648\u0627\u0644\u0627\u062a\u0633\u0627\u0642. \u062a\u0639\u0645\u0644 \u0639\u0644\u0649 \u0645\u0648\u0627\u0621\u0645\u0629 \u0627\u0644\u0639\u0645\u0644\u064a\u0627\u062a \u0645\u0639 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0648\u0627\u0644\u0644\u0648\u0627\u0626\u062d \u0648\u063a\u064a\u0631\u0647\u0627.<\/dd>\n<\/dl>\n<dl>\n<dt>\n<h5><strong>\u0627\u0644\u0645\u0639\u0627\u0644\u062c\u0629 \u0627\u0644\u062e\u0627\u0636\u0639\u0629 \u0644\u0644\u0631\u0642\u0627\u0628\u0629 \u0648\u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u062c\u0648\u062f\u0629:<\/strong><\/h5>\n<\/dt>\n<dd>\u064a\u062a\u0645 \u062a\u0646\u0641\u064a\u0630 \u0639\u0645\u0644\u064a\u0627\u062a \u0625\u0639\u0627\u062f\u0629 \u0627\u0644\u062a\u062f\u0641\u0642 \u0648\u0627\u0644\u0637\u0644\u0627\u0621 \u0648\u0627\u0644\u062a\u0634\u0630\u064a\u0628 \u0648\u0627\u0644\u062a\u0634\u0643\u064a\u0644 \u062a\u062d\u062a \u0636\u0648\u0627\u0628\u0637 \u0635\u0627\u0631\u0645\u0629 \u0644\u0636\u0645\u0627\u0646 \u0627\u0644\u062f\u0642\u0629 \u0627\u0644\u0647\u064a\u0643\u0644\u064a\u0629 \u0648\u0627\u0644\u0633\u0644\u0627\u0645\u0629 \u0627\u0644\u0643\u0647\u0631\u0628\u0627\u0626\u064a\u0629. \u062a\u0643\u062a\u0634\u0641 \u0639\u0645\u0644\u064a\u0627\u062a \u0627\u0644\u0641\u062d\u0635 \u0627\u0644\u062e\u0627\u0631\u062c\u064a \u0627\u0644\u0645\u0634\u0627\u0643\u0644 \u0641\u064a \u0648\u0642\u062a \u0645\u0628\u0643\u0631.<\/dd>\n<\/dl>\n<dl>\n<dt>\n<h5><strong>\u0627\u0644\u062a\u062d\u0642\u0642 \u0627\u0644\u0646\u0647\u0627\u0626\u064a \u0648\u0627\u0644\u062a\u0633\u0644\u064a\u0645 \u0627\u0644\u0622\u0645\u0646:<\/strong><\/h5>\n<\/dt>\n<dd>\u0627\u0644\u0627\u062e\u062a\u0628\u0627\u0631 \u0648\u0627\u0644\u062a\u0639\u0628\u0626\u0629 \u0648\u0627\u0644\u062a\u063a\u0644\u064a\u0641 \u0644\u0644\u062a\u062d\u0642\u0642 \u0645\u0646 \u0635\u062d\u0629 \u0627\u0644\u0648\u0638\u064a\u0641\u0629 \u0648\u0627\u0644\u0645\u062a\u0627\u0646\u0629. \u062a\u0636\u0645\u0646 \u0627\u0644\u0633\u062c\u0644\u0627\u062a \u0627\u0644\u0642\u0627\u0628\u0644\u0629 \u0644\u0644\u062a\u062a\u0628\u0639 \u0648\u0627\u0644\u062a\u063a\u0644\u064a\u0641 \u0627\u0644\u0648\u0642\u0627\u0626\u064a \u0627\u0644\u0634\u062d\u0646 \u0627\u0644\u0622\u0645\u0646 \u0648\u062b\u0642\u0629 \u0627\u0644\u0639\u0645\u0644\u0627\u0621.<\/dd>\n<\/dl>\n\n\t\t<\/div>\n\t<\/div>\n<div id=\"wd-6924695183a1d\" class=\"wd-rs-6924695183a1d vc_custom_1763993958558 wd-button-wrapper wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn text-center\"><a href=\"https:\/\/www.goodworksemi.com\/about-us\/contact-us\/\" title=\"\" class=\"btn btn-style-default btn-shape-rectangle btn-size-default\">\u0627\u062a\u0635\u0644 \u0628\u0646\u0627<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1766307610114 wd-disable-overflow wd-rs-6947b712d4b34\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-62b1e99b8e075\" class=\"wd-image wd-wpb wd-rs-62b1e99b8e075 text-center vc_custom_1655826871925\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"1440\" height=\"450\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/payment-and-delivery.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/payment-and-delivery.jpg 1440w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/payment-and-delivery-1200x375.jpg 1200w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/payment-and-delivery-300x94.jpg 300w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/payment-and-delivery-1024x320.jpg 1024w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/payment-and-delivery-768x240.jpg 768w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"wd-6947bfa557b5c\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-6947bfa557b5c text-left  changwenben\">\n\t\t\t<table>\n<tbody>\n<tr>\n<td width=\"214\"><span style=\"color: #1f3666;\"><strong>\u0646\u0638\u0631\u0629 \u0639\u0627\u0645\u0629 \u0639\u0644\u0649 \u0634\u0647\u0627\u062f\u0629 \u0646\u0638\u0627\u0645 \u0627\u0644\u0634\u0631\u0643\u0629<\/strong><\/span><\/td>\n<td width=\"214\"><span style=\"color: #1f3666;\"><strong>\u0646\u0638\u0627\u0645 \u0627\u0644\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0631\u0642\u0645\u064a\u0629 <\/strong><\/span><\/td>\n<td width=\"214\"><span style=\"color: #1f3666;\"><strong>\u0627\u0644\u0642\u062f\u0631\u0629 \u0627\u0644\u0645\u0624\u0633\u0633\u064a\u0629 <\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"214\"><span style=\"color: #ff6600;\"><strong>\u221a<\/strong><\/span> \u0645\u0635\u0641\u0648\u0641\u0629 \u0627\u0639\u062a\u0645\u0627\u062f \u0627\u0644\u0646\u0638\u0627\u0645<\/td>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u0646\u0638\u0627\u0645 \u0625\u062f\u0627\u0631\u0629 \u0639\u0645\u0644\u064a\u0627\u062a \u0646\u0638\u0627\u0645 \u062a\u062e\u0637\u064a\u0637 \u0645\u0648\u0627\u0631\u062f \u0627\u0644\u0645\u0624\u0633\u0633\u0627\u062a<\/td>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u0628\u0646\u0627\u0621 \u0627\u0644\u0642\u062f\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u062a\u0633\u0644\u064a\u0645 \u0648\u0642\u064a\u0645\u0629 \u0627\u0644\u0639\u0644\u0627\u0645\u0629 \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629<\/td>\n<\/tr>\n<tr>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u0646\u0638\u0627\u0645 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 ISO9001 ISO9001<\/td>\n<td width=\"214\"><span style=\"color: #ff6600;\"><strong>\u221a <\/strong><\/span>\u0646\u0638\u0627\u0645 \u062a\u0646\u0641\u064a\u0630 \u0627\u0644\u062a\u0635\u0646\u064a\u0639 MES<\/td>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>3,000 \u0645\u062a\u0631 \u0645\u0631\u0628\u0639 \u0645\u0646 \u0627\u0644\u0645\u0633\u062a\u0648\u062f\u0639\u0627\u062a \u0627\u0644\u0630\u0643\u064a\u0629\u060c \u0627\u0633\u062a\u062c\u0627\u0628\u0629 \u0633\u0631\u064a\u0639\u0629<\/td>\n<\/tr>\n<tr>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u0646\u0638\u0627\u0645 \u0627\u0644\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0628\u064a\u0626\u064a\u0629 ISO14001<\/td>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u0646\u0638\u0627\u0645 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u0633\u062a\u0648\u062f\u0639\u0627\u062a<\/td>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u062a\u0648\u0641\u064a\u0631 \u062d\u0644\u0648\u0644 \u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0645\u062e\u0635\u0635\u0629 \u0639\u0644\u0649 \u0627\u0644\u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0635\u0646\u0627\u0639\u064a \u0648\u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a<\/td>\n<\/tr>\n<tr>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u0646\u0638\u0627\u0645 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0641\u064a \u0627\u0644\u0633\u064a\u0627\u0631\u0627\u062a IATF16949 IATF16949<\/td>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u062a\u0637\u0628\u064a\u0642\u0627\u062a \u0627\u0644\u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0631\u0642\u0645\u064a\u0629<\/td>\n<td width=\"214\"><strong><span style=\"color: #ff6600;\">\u221a<\/span> <\/strong>\u0642\u0627\u0639\u062f\u0629 \u062a\u0639\u0627\u0648\u0646 \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0623\u0637\u0631\u0627\u0641 \u0628\u064a\u0646 \u0627\u0644\u0635\u0646\u0627\u0639\u0629 \u0648\u0627\u0644\u0623\u0648\u0633\u0627\u0637 \u0627\u0644\u0623\u0643\u0627\u062f\u064a\u0645\u064a\u0629 \u0648\u0627\u0644\u0628\u062d\u0648\u062b<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1669040115462 wd-rs-637b87ee10449\"><div class=\"wpb_column vc_column_container vc_col-sm-12 wd-rs-63514c8260958\"><div class=\"vc_column-inner vc_custom_1666272391679\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-69246cc921b17\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-69246cc921b17 wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xxl\" >\u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0627\u0644\u0645\u062a\u0639\u0627\u0648\u0646\u0648\u0646<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-6923c0aa7eec3\" class=\"wd-image wd-wpb wd-rs-6923c0aa7eec3 text-center vc_custom_1763950800798\">\n\t\t\t\n\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1080\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2.png 2560w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2-1200x506.png 1200w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2-300x127.png 300w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2-1024x432.png 1024w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2-768x324.png 768w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2-1536x648.png 1536w, https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/coopration-2-2048x864.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1763951277416 vc_row-has-fill wd-rs-6923c2a573e99\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-3 vc_col-md-3\"><div class=\"vc_column-inner vc_custom_1496922421269\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5c18eac89ca51\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5c18eac89ca51 wd-title-color-primary wd-title-style-default text-left vc_custom_1545136845992 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >\u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u0645\u0645\u064a\u0632\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"widget_products\"><div class=\"widget woocommerce widget_products\"><ul class=\"product_list_widget\"><li>\n\t\t<span class=\"widget-product-wrap\">\n\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/p4ke43ca-do41\/\" title=\"P4KE43CA-DO41\" class=\"widget-product-img\">\n\t\t\t<img decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/P4KE43CA-DO41-65x74.jpg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t\t<span class=\"widget-product-info\">\n\t\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/p4ke43ca-do41\/\" title=\"P4KE43CA-DO41\" class=\"wd-entities-title\">\n\t\t\t\tP4KE43CA-DO41\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"price\"><\/span>\n\t\t<\/span>\n\t<\/span>\n\t<\/li>\n<li>\n\t\t<span class=\"widget-product-wrap\">\n\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/abs6\/\" title=\"ABS6\" class=\"widget-product-img\">\n\t\t\t<img decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/ABS6-ABS-65x74.jpg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t\t<span class=\"widget-product-info\">\n\t\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/abs6\/\" title=\"ABS6\" class=\"wd-entities-title\">\n\t\t\t\tABS6\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"price\"><\/span>\n\t\t<\/span>\n\t<\/span>\n\t<\/li>\n<li>\n\t\t<span class=\"widget-product-wrap\">\n\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/abs10\/\" title=\"ABS10\" class=\"widget-product-img\">\n\t\t\t<img decoding=\"async\" width=\"65\" height=\"74\" src=\"https:\/\/www.goodworksemi.com\/wp-content\/uploads\/2025\/11\/ABS10-ABS-65x74.jpg\" class=\"attachment-65x74 size-65x74\" alt=\"\" \/>\t\t<\/a>\n\t\t<span class=\"widget-product-info\">\n\t\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/abs10\/\" title=\"ABS10\" class=\"wd-entities-title\">\n\t\t\t\tABS10\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"price\"><\/span>\n\t\t<\/span>\n\t<\/span>\n\t<\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-3 vc_col-md-3\"><div class=\"vc_column-inner vc_custom_1496922433893\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-5c18eacf2221b\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-5c18eacf2221b wd-title-color-primary wd-title-style-default text-left vc_custom_1545136851882 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >\u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062c\u062f\u064a\u062f\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"widget_products\"><div class=\"widget woocommerce widget_products\"><ul class=\"product_list_widget\"><li>\n\t\t<span class=\"widget-product-wrap\">\n\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/ss320f\/\" title=\"SS320F\" class=\"widget-product-img\">\n\t\t\t\t\t<\/a>\n\t\t<span class=\"widget-product-info\">\n\t\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/ss320f\/\" title=\"SS320F\" class=\"wd-entities-title\">\n\t\t\t\tSS320F\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"price\"><\/span>\n\t\t<\/span>\n\t<\/span>\n\t<\/li>\n<li>\n\t\t<span class=\"widget-product-wrap\">\n\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/db102s\/\" title=\"DB102S\" class=\"widget-product-img\">\n\t\t\t\t\t<\/a>\n\t\t<span class=\"widget-product-info\">\n\t\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/db102s\/\" title=\"DB102S\" class=\"wd-entities-title\">\n\t\t\t\tDB102S\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"price\"><\/span>\n\t\t<\/span>\n\t<\/span>\n\t<\/li>\n<li>\n\t\t<span class=\"widget-product-wrap\">\n\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/rl156\/\" title=\"RL156\" class=\"widget-product-img\">\n\t\t\t\t\t<\/a>\n\t\t<span class=\"widget-product-info\">\n\t\t\t<a href=\"https:\/\/www.goodworksemi.com\/ar\/products\/rl156\/\" title=\"RL156\" class=\"wd-entities-title\">\n\t\t\t\tRL156\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"price\"><\/span>\n\t\t<\/span>\n\t<\/span>\n\t<\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-6 vc_col-md-6 vc_col-has-fill wd-rs-6923c1ecb1e5d\"><div class=\"vc_column-inner vc_custom_1763951095352\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1763951230827 vc_row-has-fill wd-rs-6923c2772c4cd\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1491927161549\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6923c4c1beac1\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6923c4c1beac1 wd-title-color-primary wd-title-style-default text-center vc_custom_1763951815968 wd-width-enabled wd-underline-colored\" style=\"--wd-max-width: 70%;\">\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"title-subtitle  subtitle-color-primary font-default subtitle-style-default wd-font-weight-700 wd-fontsize-xs\">\u0625\u0644\u0649 \u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u062c\u064a\u062f<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0627\u0628\u062f\u0623 \u062a\u0635\u0645\u064a\u0645 \u0645\u0634\u0631\u0648\u0639\u0643 \u0641\u064a 3 \u062e\u0637\u0648\u0627\u062a<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child  wd-fontsize-xs\">1. \u0627\u062e\u062a\u0631 \u0627\u0644\u062e\u062f\u0645\u0629 \u0648\u0642\u062f\u0645 \u0627\u0644\u0645\u062a\u0637\u0644\u0628\u0627\u062a.<br \/>\n2. \u062a\u0623\u0643\u064a\u062f \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0648\u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0639\u0631\u0636 \u0623\u0633\u0639\u0627\u0631.<br \/>\n3. \u0627\u062f\u0641\u0639 \u0644\u0628\u062f\u0621 \u0627\u0644\u062a\u0635\u0645\u064a\u0645<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div id=\"wd-610140358df3b\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-610140358df3b wd-title-color-default wd-title-style-bordered text-center vc_custom_1627471936259 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0623\u0648 \u062a\u0627\u0628\u0639\u0646\u0627<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t<div id=\"\" class=\"wd-social-icons  wd-style-bordered wd-size-small social-share wd-shape-circle color-scheme-dark text-center\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/www.goodworksemi.com\/ar\/products\/rl156\/\" target=\"_blank\" class=\"wd-social-icon social-facebook\" aria-label=\"\u0631\u0627\u0628\u0637 \u0641\u064a\u0633\u0628\u0648\u0643 \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/x.com\/share?url=https:\/\/www.goodworksemi.com\/ar\/products\/rl156\/\" target=\"_blank\" class=\"wd-social-icon social-twitter\" aria-label=\"\u0631\u0627\u0628\u0637 \u0627\u062c\u062a\u0645\u0627\u0639\u064a X\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.goodworksemi.com\/ar\/products\/rl156\/&media=https:\/\/www.goodworksemi.com\/wp-includes\/images\/media\/default.svg&description=RL156\" target=\"_blank\" class=\"wd-social-icon social-pinterest\" aria-label=\"\u0631\u0627\u0628\u0637 Pinterest \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.goodworksemi.com\/ar\/products\/rl156\/\" target=\"_blank\" class=\"wd-social-icon social-linkedin\" aria-label=\"\u0631\u0627\u0628\u0637 Linkedin \u0627\u0644\u0627\u062c\u062a\u0645\u0627\u0639\u064a\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1763993821193 vc_row-has-fill wd-disable-overflow wd-row-gradient-enable wd-bg-center-center wd-rs-692468d4983fc\"><div class=\"woodmart-row-gradient wd-fill\" style=\"background-image:-webkit-linear-gradient(left , rgba(0, 0, 0, 0.47) , rgba(0, 0, 0, 0.557) 100%);background-image:linear-gradient(to right , rgba(0, 0, 0, 0.47) , rgba(0, 0, 0, 0.557) 100%);\"><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 color-scheme-light\"><div class=\"vc_column-inner vc_custom_1533210588709\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6923c3f5c460f\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6923c3f5c460f wd-title-color-primary wd-title-style-bordered text-center vc_custom_1763951621190 wd-underline-colored\">\n\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"title-subtitle  subtitle-color-primary font-default subtitle-style-default wd-font-weight- wd-fontsize-xs\">\u0639\u0646\u0635\u0631 \u0627\u0644\u0639\u0645\u0644 \u0627\u0644\u062c\u064a\u062f<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >\u0641\u0644\u0627\u062a\u0631 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0630\u0627\u062a \u0627\u0644\u062e\u0644\u0641\u064a\u0629 \u0627\u0644\u0645\u062e\u0635\u0635\u0629<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-filters-wrapp wd-wpb wd-rs-6190ebfcec12f wd-wpb vc_custom_1636887553159\">\n\t\t\n\t\t<form id=\"wd-6a04d64366490\" action=\"https:\/\/www.goodworksemi.com\/ar\/products\/\" class=\"wd-product-filters wd-grid-f-stretch color-scheme-dark wd-style-form\" method=\"GET\" style=\"--wd-gap-lg:10px;\" data-trp-original-action=\"https:\/\/www.goodworksemi.com\/ar\/products\/\">\n\t\t\t\t\t\t<div id=\"wd-6a04d64366616\" class=\"wd-pf-checkboxes wd-col wd-pf-categories wd-event-click\">\n\t\t\t<div class=\"wd-pf-title\">\n\t\t\t\t<span class=\"title-text\">\n\t\t\t\t\t\u0627\u0644\u0641\u0626\u0627\u062a\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<ul class=\"wd-pf-results\">\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"wd-pf-dropdown wd-dropdown\">\n\t\t\t\t<div class=\"wd-scroll\">\n\t\t\t\t\t<ul class=\"wd-scroll-content\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"cat-item cat-item-72\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/bridge-rectifiers\/\" data-val=\"bridge-rectifiers\" data-title=\"Bridge Rectifiers\" >\u0645\u0642\u0648\u0645\u0627\u062a \u0627\u0644\u062c\u0633\u0631<\/a>\n<ul class='children'>\n\t<li class=\"cat-item cat-item-79\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/bridge-rectifiers\/fast-recovery-rectifier-bridge\/\" data-val=\"fast-recovery-rectifier-bridge\" data-title=\"Fast Recovery Rectifier Bridge\" >\u062c\u0633\u0631 \u0645\u0642\u0648\u0645 \u0627\u0644\u0627\u0633\u062a\u0631\u062f\u0627\u062f \u0627\u0644\u0633\u0631\u064a\u0639<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-82\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/bridge-rectifiers\/general-rectifier-bridge\/\" data-val=\"general-rectifier-bridge\" data-title=\"General Rectifier Bridge\" >\u062c\u0633\u0631 \u0627\u0644\u0645\u0642\u0648\u0645 \u0627\u0644\u0639\u0627\u0645<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-21\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/bridge-rectifiers\/high-frequency-rectifier-bridge\/\" data-val=\"high-frequency-rectifier-bridge\" data-title=\"High Frequency Rectifier Bridge\" >\u062c\u0633\u0631 \u0645\u0642\u0648\u0645 \u0627\u0644\u062a\u0631\u062f\u062f\u0627\u062a \u0627\u0644\u0639\u0627\u0644\u064a\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-81\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/bridge-rectifiers\/schottky-bridge\/\" data-val=\"schottky-bridge\" data-title=\"Schottky Bridge\" >\u062c\u0633\u0631 \u0634\u0648\u062a\u0643\u064a<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-80\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/bridge-rectifiers\/ultra-fast-recovery-rectifier-bridge\/\" data-val=\"ultra-fast-recovery-rectifier-bridge\" data-title=\"Ultra Fast Recovery Rectifier Bridge\" >\u062c\u0633\u0631 \u0645\u0642\u0648\u0645 \u0627\u0644\u0627\u0633\u062a\u0631\u062f\u0627\u062f \u0627\u0644\u0633\u0631\u064a\u0639 \u0644\u0644\u063a\u0627\u064a\u0629<\/a>\n<\/li>\n<\/ul>\n<\/li>\n\t<li class=\"cat-item cat-item-73\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/\" data-val=\"diodes\" data-title=\"Diodes\" >\u0627\u0644\u062b\u0646\u0627\u0626\u064a\u0627\u062a<\/a>\n<ul class='children'>\n\t<li class=\"cat-item cat-item-84\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/esd-protection-diodes\/\" data-val=\"esd-protection-diodes\" data-title=\"ESD Protection Diodes\" >\u0635\u0645\u0627\u0645\u0627\u062a \u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0627\u0644\u062d\u0645\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0641\u0631\u064a\u063a \u0627\u0644\u0643\u0647\u0631\u0648\u0645\u063a\u0646\u0627\u0637\u064a\u0633\u064a \u0627\u0644\u062b\u0646\u0627\u0626\u064a<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-91\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/fast-recovery-diodes\/\" data-val=\"fast-recovery-diodes\" data-title=\"Fast Recovery Diodes\" >\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0627\u0644\u0627\u0633\u062a\u0631\u062f\u0627\u062f \u0627\u0644\u0633\u0631\u064a\u0639<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-94\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/general-rectifier-diodes\/\" data-val=\"general-rectifier-diodes\" data-title=\"General Rectifier Diodes\" >\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0627\u0644\u0645\u0642\u0648\u0645 \u0627\u0644\u0639\u0627\u0645<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-113\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/high-frequency-diodes\/\" data-val=\"high-frequency-diodes\" data-title=\"High Frequency Diodes\" >\u0627\u0644\u0635\u0645\u0627\u0645\u0627\u062a \u0627\u0644\u062b\u0646\u0627\u0626\u064a\u0629 \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062a\u0631\u062f\u062f<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-146\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/high-voltage-diodes\/\" data-val=\"high-voltage-diodes\" data-title=\"High-Voltage Diodes\" >\u0627\u0644\u0635\u0645\u0627\u0645\u0627\u062a \u0627\u0644\u062b\u0646\u0627\u0626\u064a\u0629 \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062c\u0647\u062f<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-86\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/planar-schottky-diodes\/\" data-val=\"planar-schottky-diodes\" data-title=\"Planar Schottky Diodes\" >\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0634\u0648\u062a\u0643\u064a \u0627\u0644\u0645\u0633\u062a\u0648\u064a\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-145\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/pv-diodes\/\" data-val=\"pv-diodes\" data-title=\"PV Diodes\" >\u0627\u0644\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0627\u0644\u0643\u0647\u0631\u0648\u0636\u0648\u0626\u064a\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-89\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/schottky-diodes\/\" data-val=\"schottky-diodes\" data-title=\"Schottky Diodes\" >\u0635\u0645\u0627\u0645\u0627\u062a \u0634\u0648\u062a\u0643\u064a \u0627\u0644\u062b\u0646\u0627\u0626\u064a\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-125\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/small-signal-diodes\/\" data-val=\"small-signal-diodes\" data-title=\"Small Signal Diodes\" >\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0627\u0644\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u063a\u064a\u0631\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-95\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/transient-voltage-suppressors\/\" data-val=\"transient-voltage-suppressors\" data-title=\"Transient Voltage Suppressors\" >\u0643\u0627\u0628\u062a\u0627\u062a \u0627\u0644\u062c\u0647\u062f \u0627\u0644\u0639\u0627\u0628\u0631<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-87\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/trench-schottky-diodes\/\" data-val=\"trench-schottky-diodes\" data-title=\"Trench Schottky Diodes\" >\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0634\u0648\u062a\u0643\u064a \u0627\u0644\u062e\u0646\u062f\u0642<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-93\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/ultra-fast-recovery-diodes\/\" data-val=\"ultra-fast-recovery-diodes\" data-title=\"Ultra-Fast Recovery Diodes\" >\u062b\u0646\u0627\u0626\u064a\u0627\u062a \u0627\u0644\u0627\u0633\u062a\u0631\u062f\u0627\u062f \u0641\u0627\u0626\u0642 \u0627\u0644\u0633\u0631\u0639\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-96\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/diodes\/zener-diodes\/\" data-val=\"zener-diodes\" data-title=\"Zener Diodes\" >\u0635\u0645\u0627\u0645\u0627\u062a \u0632\u064a\u0646\u0631 \u0627\u0644\u062b\u0646\u0627\u0626\u064a\u0629<\/a>\n<\/li>\n<\/ul>\n<\/li>\n\t<li class=\"cat-item cat-item-74\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/lithium-battery-protection\/\" data-val=\"lithium-battery-protection\" data-title=\"Lithium battery protection\" >\u062d\u0645\u0627\u064a\u0629 \u0628\u0637\u0627\u0631\u064a\u0629 \u0627\u0644\u0644\u064a\u062b\u064a\u0648\u0645<\/a>\n<ul class='children'>\n\t<li class=\"cat-item cat-item-130\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/lithium-battery-protection\/ordinary-single-cell-protection-series\/\" data-val=\"ordinary-single-cell-protection-series\" data-title=\"Ordinary Single Cell Protection Series\" >\u0633\u0644\u0633\u0644\u0629 \u0627\u0644\u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u0639\u0627\u062f\u064a\u0629 \u0623\u062d\u0627\u062f\u064a\u0629 \u0627\u0644\u062e\u0644\u064a\u0629 \u0627\u0644\u0639\u0627\u062f\u064a\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-131\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/lithium-battery-protection\/single-cell-protection-two-in-one-series\/\" data-val=\"single-cell-protection-two-in-one-series\" data-title=\"Single Cell Protection Two-in-one Series\" >\u0633\u0644\u0633\u0644\u0629 \u062d\u0645\u0627\u064a\u0629 \u0627\u0644\u062e\u0644\u064a\u0629 \u0627\u0644\u0648\u0627\u062d\u062f\u0629 \u062b\u0646\u0627\u0626\u064a \u0641\u064a \u0648\u0627\u062d\u062f<\/a>\n<\/li>\n<\/ul>\n<\/li>\n\t<li class=\"cat-item cat-item-75\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/low-dropout-regulator\/\" data-val=\"low-dropout-regulator\" data-title=\"Low Dropout Regulator\" >\u0645\u0646\u0638\u0645 \u0627\u0644\u062a\u0633\u0631\u0628 \u0627\u0644\u0645\u0646\u062e\u0641\u0636<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-110\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/mini-bridge\/\" data-val=\"mini-bridge\" data-title=\"MINI Bridge\" >\u062c\u0633\u0631 \u0645\u064a\u0646\u064a<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-76\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/mosfets\/\" data-val=\"mosfets\" data-title=\"MOSFETs\" >\u0645\u062a\u0641\u062a\u062a\u0627\u062a MOSFETs<\/a>\n<ul class='children'>\n\t<li class=\"cat-item cat-item-99\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/mosfets\/cool-mos\/\" data-val=\"cool-mos\" data-title=\"Cool MOS\" >\u0646\u0638\u0627\u0645 \u0627\u0644\u062a\u0634\u063a\u064a\u0644 MOS \u0627\u0644\u0631\u0627\u0626\u0639<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-102\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/mosfets\/sgt-mos\/\" data-val=\"sgt-mos\" data-title=\"SGT MOS\" >\u0627\u0644\u0631\u0642\u064a\u0628 \u0623\u0648\u0644 \u0645.\u0639.\u062d.\u0639.\u0633<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-104\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/mosfets\/sic-mos\/\" data-val=\"sic-mos\" data-title=\"SiC MOS\" >SiC MOS<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-103\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/mosfets\/trench-mos\/\" data-val=\"trench-mos\" data-title=\"Trench MOS\" >\u062e\u0646\u062f\u0642 MOS<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-100\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/mosfets\/vdmos\/\" data-val=\"vdmos\" data-title=\"VDMOS\" >VDMOS<\/a>\n<\/li>\n<\/ul>\n<\/li>\n\t<li class=\"cat-item cat-item-77\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/photocouplers\/\" data-val=\"photocouplers\" data-title=\"Photocouplers\" >\u0627\u0644\u0645\u0642\u0631\u0648\u0636\u0627\u062a \u0627\u0644\u0636\u0648\u0626\u064a\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-109\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/thyristor\/\" data-val=\"thyristor\" data-title=\"Thyristor\" >\u0627\u0644\u062b\u0627\u064a\u0631\u0633\u062a\u0648\u0631<\/a>\n<ul class='children'>\n\t<li class=\"cat-item cat-item-126\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/thyristor\/bidirectional-thyristor\/\" data-val=\"bidirectional-thyristor\" data-title=\"Bidirectional thyristor\" >\u062b\u0627\u064a\u0631\u0633\u062a\u0648\u0631 \u062b\u0646\u0627\u0626\u064a \u0627\u0644\u0627\u062a\u062c\u0627\u0647<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-127\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/thyristor\/sensitive-gate-unidirectional-thyristor\/\" data-val=\"sensitive-gate-unidirectional-thyristor\" data-title=\"Sensitive gate unidirectional thyristor\" >\u0628\u0648\u0627\u0628\u0629 \u062d\u0633\u0627\u0633\u0629 \u0623\u062d\u0627\u062f\u064a\u0629 \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u062b\u0627\u064a\u0631\u0633\u062a\u0648\u0631 \u0623\u062d\u0627\u062f\u064a \u0627\u0644\u0627\u062a\u062c\u0627\u0647<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-128\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/thyristor\/standard-unidirectional-thyristor\/\" data-val=\"standard-unidirectional-thyristor\" data-title=\"Standard unidirectional thyristor\" >\u062b\u0627\u064a\u0631\u0633\u062a\u0648\u0631 \u0623\u062d\u0627\u062f\u064a \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0642\u064a\u0627\u0633\u064a<\/a>\n<\/li>\n<\/ul>\n<\/li>\n\t<li class=\"cat-item cat-item-78\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/transistors\/\" data-val=\"transistors\" data-title=\"Transistors\" >\u0627\u0644\u062a\u0631\u0627\u0646\u0632\u0633\u062a\u0648\u0631\u0627\u062a<\/a>\n<ul class='children'>\n\t<li class=\"cat-item cat-item-105\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/transistors\/darlington-transistor\/\" data-val=\"darlington-transistor\" data-title=\"Darlington Transistor\" >\u062a\u0631\u0627\u0646\u0632\u0633\u062a\u0648\u0631 \u062f\u0627\u0631\u0644\u064a\u0646\u062c\u062a\u0648\u0646<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-106\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/transistors\/digital-transistor\/\" data-val=\"digital-transistor\" data-title=\"Digital Transistor\" >\u062a\u0631\u0627\u0646\u0632\u0633\u062a\u0648\u0631 \u0631\u0642\u0645\u064a<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-107\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/transistors\/power-transistor\/\" data-val=\"power-transistor\" data-title=\"Power Transistor\" >\u062a\u0631\u0627\u0646\u0632\u0633\u062a\u0648\u0631 \u0627\u0644\u0637\u0627\u0642\u0629<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-108\"><a class=\"pf-value\" href=\"https:\/\/www.goodworksemi.com\/ar\/product-category\/transistors\/small-signal-transistor\/\" data-val=\"small-signal-transistor\" data-title=\"Small Signal Transistor\" >\u062a\u0631\u0627\u0646\u0632\u0633\u062a\u0648\u0631 \u0627\u0644\u0625\u0634\u0627\u0631\u0627\u062a \u0627\u0644\u0635\u063a\u064a\u0631\u0629<\/a>\n<\/li>\n<\/ul>\n<\/li>\n\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-pf-btn wd-col\">\n\t\t\t\t\t<button type=\"submit\">\n\t\t\t\t\t\t\u0627\u0644\u062a\u0635\u0641\u064a\u0629\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Part Number VRRM(V) I(AV)A IFSM(A) VF(V) IF\uff08A\uff09 IR(\u03bcA) VR(V) Package outline RL156 800 1.5 50 1 1.5 5 800 DO-15","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5639","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.goodworksemi.com\/ar\/wp-json\/wp\/v2\/pages\/5639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodworksemi.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.goodworksemi.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodworksemi.com\/ar\/wp-json\/wp\/v2\/comments?post=5639"}],"version-history":[{"count":0,"href":"https:\/\/www.goodworksemi.com\/ar\/wp-json\/wp\/v2\/pages\/5639\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.goodworksemi.com\/ar\/wp-json\/wp\/v2\/media?parent=5639"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}